{"id":60383,"date":"2022-02-28T06:30:00","date_gmt":"2022-02-28T13:30:00","guid":{"rendered":"https:\/\/www.moosepeterson.com\/blog\/?p=60383"},"modified":"2022-07-07T19:28:02","modified_gmt":"2022-07-08T01:28:02","slug":"moose-podcast-281-whats-in-a-title","status":"publish","type":"post","link":"https:\/\/www.moosepeterson.com\/blog\/moose-podcast-281-whats-in-a-title\/","title":{"rendered":"Moose Podcast #281 &#8211; &#8220;What&#8217;s In a Title?&#8221;"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2022\/02\/Yellowstone-50259.jpg&#8221; alt=&#8221;Aero C-104&#8243; title_text=&#8221;Yellowstone 50259&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Terrace Hot Spring, Yellowstone captured by Z 9 \/ Z70-200f2.8<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; custom_padding=&#8221;18px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>This episode of the Moose Podcast #281 &#8211; &#8220;What&#8217;s In a Title? &#8220;, Our direction came from a title over forty years ago. Titles since have stopped me in m tracks. We love to give things titles but do they help move our photography forward?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;21px&#8221; custom_padding=&#8221;17px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Click to listen to Episode 281<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_audio audio=&#8221;https:\/\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2022\/02\/Podcast2812.mp3&#8243; _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;Podcast281#2&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_audio][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;24px&#8221; text_line_height=&#8221;1.6em&#8221; custom_padding=&#8221;17px||||false|false&#8221; text_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>and you can listen to it here:<br \/><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/moose-podcast\/id1107405746\"><strong>iTunes<\/strong><\/a><br \/>\n<strong><a href=\"https:\/\/music.amazon.com\/podcasts\/a342e8ec-b67c-425a-9559-5c0a4584255f\">Amazon<\/a><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;17px&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Howdy and welcome to the Moose Podcast! Thanks for taking the time to drop in from your week to listen! Thank you folks for listening and continually rising the Moose Podcast in the ratings &#8230; thank you ever so much! Please be so kind and continue to Tweet and\/or share on the Moose Podcast on Facebook! I&#8217;d be grateful for your continuation in doing that. Want to hear about a particular topic, send in the suggestion &#8230; send them to <strong><a href=\"mailto:info@moosepeterson.com?subject=I%20have a question for the Moose Podcast!\">Moose Podcast<\/a><\/strong>. THANKS! (sorry, emails sent to this address will get no direct response).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;17px&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>People, Companies, Products Mentioned during Podcast<\/strong>:<br \/><a href=\"https:\/\/www.bedfords.com\/\"><strong>Bedford Camera<\/strong><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our direction came from a title over forty years ago. Titles since have stopped my in m tracks. We love to give things titles but do they help move our photography forward?<\/p>\n","protected":false},"author":1,"featured_media":57019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1219","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","sync_status":"failed","episode_type":"audio","audio_file":"https:\/\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2022\/02\/Podcast281.mp3","podmotor_file_id":"","podmotor_episode_id":"","castos_file_data":"","cover_image":"","cover_image_id":"","duration":"15:40","filesize":"28.68M","filesize_raw":"30073680","date_recorded":"2022-02-28 06:30:00","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Moose Podcast #281 - \"What's In a Title?\" https:\/\/wp.me\/p6YJx-fHV we love creating them, but do we need the and do they constrain our photography? @BedfordCamera @NikonUS #nikonambassador","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[314],"tags":[],"series":[298],"class_list":["post-60383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast","series-moose-podcasts"],"episode_featured_image":"https:\/\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2021\/05\/MoosePodcastNS.jpg","episode_player_image":"https:\/\/i0.wp.com\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2018\/06\/Podcast.jpg?fit=1500%2C1500&quality=100&ssl=1","download_link":"https:\/\/www.moosepeterson.com\/blog\/podcast-download\/60383\/moose-podcast-281-whats-in-a-title","player_link":"https:\/\/www.moosepeterson.com\/blog\/podcast-player\/60383\/moose-podcast-281-whats-in-a-title","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/www.moosepeterson.com\/blog\/podcast-player\/60383\/moose-podcast-281-whats-in-a-title\">https:\/\/www.moosepeterson.com\/blog\/podcast-player\/60383\/moose-podcast-281-whats-in-a-title<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/us\/podcast\/moose-podcasts\/id1107405746","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/2fRA9VaVfSdQMKf1ipxr0t","label":"Spotify","class":"spotify","icon":"spotify.png"},"itunes":{"key":"itunes","url":"https:\/\/podcasts.apple.com\/us\/podcast\/moose-podcasts\/id1107405746","label":"iTunes","class":"itunes","icon":"itunes.png"}},"rssFeedUrl":"https:\/\/www.moosepeterson.com\/blog\/feed\/podcast\/moose-podcasts","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"6LJzUlxhfj\"><a href=\"https:\/\/www.moosepeterson.com\/blog\/moose-podcast-281-whats-in-a-title\/\">Moose Podcast #281 &#8211; &#8220;What&#8217;s In a Title?&#8221;<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/www.moosepeterson.com\/blog\/moose-podcast-281-whats-in-a-title\/embed\/#?secret=6LJzUlxhfj\" width=\"500\" height=\"350\" title=\"&#8220;Moose Podcast #281 &#8211; &#8220;What&#8217;s In a Title?&#8221;&#8221; &#8212; Moose Peterson&#039;s Website\" data-secret=\"6LJzUlxhfj\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/www.moosepeterson.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n","syncStatus":{"isSynced":false,"status":"failed","error":"","message":"Could not sync with Castos.","title":"Failed"}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p6YJx-fHV","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.moosepeterson.com\/blog\/wp-content\/uploads\/2021\/05\/MoosePodcastNS.jpg?fit=1200%2C850&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/posts\/60383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/comments?post=60383"}],"version-history":[{"count":3,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/posts\/60383\/revisions"}],"predecessor-version":[{"id":60395,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/posts\/60383\/revisions\/60395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/media\/57019"}],"wp:attachment":[{"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/media?parent=60383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/categories?post=60383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/tags?post=60383"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.moosepeterson.com\/blog\/wp-json\/wp\/v2\/series?post=60383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}